{"id":2099,"date":"2025-03-03T09:55:27","date_gmt":"2025-03-03T09:55:27","guid":{"rendered":"https:\/\/palermoexperiences.com\/tour\/tramonto-in-barca-alla-grotta-della-regina\/"},"modified":"2025-07-06T13:33:03","modified_gmt":"2025-07-06T13:33:03","slug":"tramonto-in-barca-alla-grotta-della-regina","status":"publish","type":"page","link":"https:\/\/palermoexperiences.com\/it\/tour\/tramonto-in-barca-alla-grotta-della-regina\/","title":{"rendered":"Tramonto in barca alla Grotta della Regina"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2099\" class=\"elementor elementor-2099 elementor-2081\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c11186c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"2c11186c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebedf08 elementor-widget elementor-widget-text-editor\" data-id=\"1ebedf08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<product-details-widget widget-id=\"06ed18c4-17ed-4a53-89c0-e4c5638bd00c\"><\/product-details-widget><script type=\"text\/javascript\" src=\"https:\/\/widgets.regiondo.net\/product\/v1\/product-widget.min.js\"><\/script>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d6cb0cb e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"d6cb0cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;fixed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-624f37e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"624f37e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wasmart.business\/model\/buttonschat\/r\/d3882a54-b35f-46bd-a179-400b20b30b4f\/639432139250410\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/palermoexperiences.com\/wp-content\/uploads\/2025\/06\/WhatsApp-2-1.png\" class=\"attachment-large size-large wp-image-3400\" alt=\"\" srcset=\"https:\/\/palermoexperiences.com\/wp-content\/uploads\/2025\/06\/WhatsApp-2-1.png 200w, https:\/\/palermoexperiences.com\/wp-content\/uploads\/2025\/06\/WhatsApp-2-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":1017,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2099","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/pages\/2099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/comments?post=2099"}],"version-history":[{"count":10,"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/pages\/2099\/revisions"}],"predecessor-version":[{"id":3691,"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/pages\/2099\/revisions\/3691"}],"up":[{"embeddable":true,"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/pages\/1017"}],"wp:attachment":[{"href":"https:\/\/palermoexperiences.com\/it\/wp-json\/wp\/v2\/media?parent=2099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}